{"id":13350,"date":"2022-03-21T16:24:21","date_gmt":"2022-03-21T14:24:21","guid":{"rendered":"https:\/\/sofiaimplantcentre.com\/quest-ce-quun-implant-dentaire\/"},"modified":"2023-09-14T16:56:13","modified_gmt":"2023-09-14T13:56:13","slug":"quest-ce-quun-implant-dentaire","status":"publish","type":"post","link":"https:\/\/sofiaimplantcentre.com\/fr\/quest-ce-quun-implant-dentaire\/","title":{"rendered":"Qu\u2019est-ce qu\u2019un implant dentaire ?"},"content":{"rendered":"<p class=\"p1\">Aujourd&rsquo;hui, les implants dentaires sont devenus le moyen privil\u00e9gi\u00e9 de traiter les dents manquantes. Voici tout ce qu&rsquo;il faut savoir sur les implants dentaires.<!--more--><\/p>\n<p><span style=\"font-weight: 400;\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12165\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/02\/implants.png\" alt=\"\" width=\"66\" height=\"100\" srcset=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/02\/implants.png 229w, https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/02\/implants-198x300.png 198w\" sizes=\"auto, (max-width: 66px) 100vw, 66px\" \/><\/span><\/p>\n<p class=\"p1\">Un implant dentaire est une petite vis en titane qui est ins\u00e9r\u00e9e chirurgicalement dans l\u2019os de la m\u00e2choire, remplissant ainsi la fonction des racines des dents manquantes. Il est fait de titane m\u00e9tallique.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Lecteur vid\u00e9os sur YouTube\" src=\"https:\/\/www.youtube.com\/embed\/hVhOvB4NMTA\" width=\"868\" height=\"488\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p class=\"p1\">Le titane est un mat\u00e9riau biologiquement tol\u00e9r\u00e9 utilis\u00e9 dans divers domaines de la m\u00e9decine. Dans le domaine dentaire, en tant qu\u2019implant, il se connecte \u00e0 l\u2019os et cr\u00e9e une base solide pour la restauration dentaire. Selon les recherches, le succ\u00e8s du traitement implantaire varie de 96% \u00e0 98%.<\/p>\n<p class=\"p1\">Une fois les implants plac\u00e9s en fonction de la mastication du patient, une couronne ou une proth\u00e8se fixe est fabriqu\u00e9e.Cette derni\u00e8re peut \u00eatre en m\u00e9tal-c\u00e9ramique, en zircone ou en un autre mat\u00e9riau. Normalement, la couronne est plac\u00e9e au moins 4 mois apr\u00e8s la pose de l\u2019implant.<\/p>\n<p><iframe loading=\"lazy\" title=\"Lecteur vid\u00e9os sur YouTube\" src=\"https:\/\/www.youtube.com\/embed\/3m1vNd7V9Gs\" width=\"868\" height=\"488\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p class=\"p1\">Ne pensez pas que les soins dentaires disparaissent apr\u00e8s la pose de l\u2019implant. Si un entretien appropri\u00e9 des implants dentaires s\u2019ensuit, ils b\u00e9n\u00e9ficient d\u2019une garantie \u00e0 vie ! Certains fabricants offrent une garantie structurelle \u00e0 vie. \u00c0 la clinique Sofia Implant Centre, nous travaillons avec de tels implants. \u00c0 l\u2019inverse, certains facteurs comme le manque d\u2019hygi\u00e8ne ou la pr\u00e9sence de mauvaises habitudes peuvent entra\u00eener une infection et la chute cons\u00e9quente de l\u2019implant.<\/p>\n<p class=\"p1\">Si vous \u00eates d\u00e9j\u00e0 convaincu des avantages des implants et imaginez d\u00e9j\u00e0 comment votre probl\u00e8me pourrait \u00eatre r\u00e9solu \u2013 ne vous pr\u00e9cipitez pas \u2013 il vous reste des d\u00e9cisions importantes \u00e0 prendre. Par exemple, quelle marque d&rsquo;implants dentaires choisir ? Dans un premier temps, est-ce que le traitement implantaire r\u00e9pond vraiment \u00e0 vos besoins sp\u00e9cifiques ? Et un tas d\u2019autres questions auxquelles nous vous donnerons les r\u00e9ponses dans les postes et vid\u00e9os qui suivent.<\/p>\n<p>Si vous souhaitez savoir comment choisir l&rsquo;implant qui vous convient le mieux, lisez l&rsquo;article suivant :<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <a href=\"https:\/\/sofiaimplantcentre.com\/how-to-choose-implants\/\" rel=\"bookmark\">Comment choisir les meilleurs implants dentaires du march\u00e9 ?<\/a><\/p>\n<p>____<\/p>\n<p><strong>Obtenez votre plan de traitement individuel gratuit aujourd&rsquo;hui !<\/strong><\/p>\n<table style=\"word-spacing: 1px; font-family: Arial,Helvetica,sans-serif; font-size: 12.8px; border: none; border-collapse: collapse; color: #222222;\">\n<tbody style=\"font-family: Arial,Helvetica,sans-serif;\">\n<tr style=\"height: 0px; font-family: Arial,Helvetica,sans-serif;\">\n<td style=\"border-style: solid; border-width: 0px 1px 0px 0px; vertical-align: top; padding: 7px; font-family: Arial,Helvetica,sans-serif; border-color: #0f75bd;\">\n<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13732 size-full\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/sara.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/sara.png 200w, https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/sara-150x150.png 150w, https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/sara-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/td>\n<td style=\"border-style: solid; border-width: 0px 0px 0px 1px; vertical-align: top; padding: 0px 11px; font-family: Arial,Helvetica,sans-serif; border-color: #0f75bd; text-align: left;\">\n<div style=\"font-size: 0.800000011920929rem; font-family: Arial,Helvetica,sans-serif;\">\n<div style=\"font-size: 0.800000011920929rem; font-family: Arial,Helvetica,sans-serif;\">\n<div style=\"font-size: 0.800000011920929rem; font-family: Arial,Helvetica,sans-serif;\">Sarah Boulhanna<br \/>\nDental Treatment Consultant (<img decoding=\"async\" class=\"an1\" style=\"width: 24px;\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/14.0\/1f1ea_1f1f8\/72.png\" alt=\"??\" data-emoji=\"??\" aria-label=\"??\" \/>\u00a0<img decoding=\"async\" class=\"an1\" style=\"width: 24px;\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/14.0\/1f1ec_1f1e7\/72.png\" alt=\"??\" data-emoji=\"??\" aria-label=\"??\" \/>\u00a0<img decoding=\"async\" class=\"an1\" style=\"width: 24px;\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/14.0\/1f1eb_1f1f7\/72.png\" alt=\"??\" data-emoji=\"??\" aria-label=\"??\" \/>)<br \/>\nUK Tel. <a href=\"tel:+44 20 4538 7222\">+44 20 4538 7222<\/a><br \/>\nBG Tel. <a href=\"tel:+359 895 269 533\">+359 895 269 533<\/a><br \/>\nWhatsApp: <a href=\"https:\/\/wa.me\/359895269533\">+359 895 269 533<\/a> (<a style=\"font-size: 0.800000011920929rem; font-family: Arial,Helvetica,sans-serif;\" href=\"https:\/\/wa.me\/359895269533\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.wa.me\/359895269533&amp;source=gmail&amp;ust=1643949131656000&amp;usg=AOvVaw3IWCaQU3hrwUNRpQs8Nma7\">click here to WhatsApp me!<\/a>)<\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\"><a style=\"font-family: Arial,Helvetica,sans-serif;\" href=\"mailto:sara@sofiaimplantcentre.com\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 0.800000011920929rem; font-family: Arial,Helvetica,sans-serif;\">sara@sofiaimplantcentre.com<\/span><\/a><\/div>\n<\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\"><div class=\"nta_wa_button\" data-id=\"9313\" data-info=\"{&quot;name&quot;:&quot;Sarah Boulhanna, Conseill\\u00e8re commerciale&quot;,&quot;info&quot;:{&quot;number&quot;:&quot;+359895269533&quot;,&quot;title&quot;:&quot;&quot;,&quot;predefinedText&quot;:&quot;&quot;,&quot;willBeBackText&quot;:&quot;I will be back in [njwa_time_work]&quot;,&quot;dayOffsText&quot;:&quot;I will be back soon&quot;,&quot;isAlwaysAvailable&quot;:&quot;ON&quot;,&quot;daysOfWeekWorking&quot;:{&quot;sunday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]},&quot;monday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]},&quot;tuesday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]},&quot;wednesday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]},&quot;thursday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]},&quot;friday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]},&quot;saturday&quot;:{&quot;isWorkingOnDay&quot;:&quot;OFF&quot;,&quot;workHours&quot;:[{&quot;startTime&quot;:&quot;08:00&quot;,&quot;endTime&quot;:&quot;17:30&quot;}]}}},&quot;styles&quot;:{&quot;type&quot;:&quot;round&quot;,&quot;backgroundColor&quot;:&quot;#2DB742&quot;,&quot;textColor&quot;:&quot;#fff&quot;,&quot;label&quot;:&quot;Envoyez-moi un SMS pour obtenir votre plan de traitement individuel d\\u00e8s maintenant !&quot;,&quot;width&quot;:300,&quot;height&quot;:64},&quot;avatar&quot;:&quot;https:\\\/\\\/sofiaimplantcentre.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/sara.png&quot;,&quot;options&quot;:{&quot;accounts&quot;:{&quot;hideOfflineAgents&quot;:&quot;OFF&quot;},&quot;display&quot;:{&quot;displayCondition&quot;:&quot;excludePages&quot;,&quot;displayPostCondition&quot;:&quot;showAllPost&quot;,&quot;includePages&quot;:[],&quot;excludePages&quot;:[&quot;28014&quot;],&quot;includePosts&quot;:[],&quot;excludePosts&quot;:[],&quot;showOnDesktop&quot;:&quot;ON&quot;,&quot;showOnMobile&quot;:&quot;ON&quot;,&quot;time_symbols&quot;:&quot;h:m&quot;},&quot;styles&quot;:{&quot;title&quot;:&quot;WhatsApp: ONLINE&quot;,&quot;responseText&quot;:&quot;&quot;,&quot;description&quot;:&quot;&quot;,&quot;backgroundColor&quot;:&quot;#2db742&quot;,&quot;textColor&quot;:&quot;#fff&quot;,&quot;titleSize&quot;:18,&quot;accountNameSize&quot;:14,&quot;descriptionTextSize&quot;:12,&quot;regularTextSize&quot;:11,&quot;scrollHeight&quot;:&quot;500&quot;,&quot;isShowScroll&quot;:&quot;OFF&quot;,&quot;isShowResponseText&quot;:&quot;OFF&quot;,&quot;btnLabel&quot;:&quot;WhatsApp: ONLINE&quot;,&quot;btnLabelWidth&quot;:&quot;108&quot;,&quot;btnPosition&quot;:&quot;right&quot;,&quot;btnLeftDistance&quot;:&quot;30&quot;,&quot;btnRightDistance&quot;:&quot;30&quot;,&quot;btnBottomDistance&quot;:&quot;30&quot;,&quot;isShowBtnLabel&quot;:&quot;ON&quot;,&quot;isShowGDPR&quot;:&quot;OFF&quot;,&quot;gdprContent&quot;:&quot;Please accept our &lt;a href=\\&quot;https:\\\/\\\/ninjateam.org\\\/privacy-policy\\\/\\&quot;&gt;privacy policy&lt;\\\/a&gt; first to start a conversation.&quot;,&quot;widgetType&quot;:&quot;expandable&quot;,&quot;isShowPoweredBy&quot;:&quot;OFF&quot;},&quot;analytics&quot;:{&quot;enabledGoogle&quot;:&quot;ON&quot;,&quot;enabledFacebook&quot;:&quot;ON&quot;,&quot;enabledGoogleGA4&quot;:&quot;ON&quot;}},&quot;gdprStatus&quot;:false,&quot;defaultAvatar&quot;:&quot;https:\\\/\\\/sofiaimplantcentre.com\\\/wp-content\\\/plugins\\\/whatsapp-for-wordpress\\\/assets\\\/img\\\/whatsapp_logo.svg&quot;}\"><\/div><\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26222\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2023\/08\/499-FR-FRENCH-PIC-pic2-1200x1200-1-300x300.png\" alt=\"\" width=\"500\" height=\"500\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Les articles et vid\u00e9os associ\u00e9s :<\/span><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/are-dental-implants-right-for-me\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a><a href=\"https:\/\/sofiaimplantcentre.com\/dental-implants-how-to-avoid-a-mistake-when-choosing-a-clinic\/\" target=\"_blank\" rel=\"bookmark noopener\">Comment ne pas se tromper en choisissant une clinique pour ses implants dentaires ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\"><a href=\"https:\/\/sofiaimplantcentre.com\/our-materials\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/><\/a> <a href=\"https:\/\/sofiaimplantcentre.com\/bg\/materiali1\/\" rel=\"bookmark\">\u00c0 quoi s\u2019attendre chez Sofia Implant Centre : les mat\u00e9riaux utilis\u00e9s, les services et normes de travail<\/a><\/span><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/are-dental-implants-right-for-me\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a><a href=\"https:\/\/sofiaimplantcentre.com\/bg\/stavam-li-sa-implanti\/\" rel=\"bookmark\">Les implants dentaires consistent-t-ils \u00e0 un traitement ad\u00e9quat pour moi ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/how-to-choose-implants\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a><a href=\"https:\/\/sofiaimplantcentre.com\/bg\/implanti\/\" rel=\"bookmark\">Comment choisir les meilleurs implants dentaires du march\u00e9 ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/cbct-3d-scan\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a> <a href=\"https:\/\/sofiaimplantcentre.com\/bg\/3d-skener\/\" rel=\"bookmark\">Pourquoi le scanner 3D CBCT est-il crucial ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/extraction-of-teeth-and-placement-of-implants\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a><a href=\"https:\/\/sofiaimplantcentre.com\/bg\/vadene-na-zyb\/\" rel=\"bookmark\">L&rsquo;extraction de dents et la pose d&rsquo;implants dentaires<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/implants-and-lack-of-bone\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a><a href=\"https:\/\/sofiaimplantcentre.com\/bg\/prisajdane-na-kost\/\" rel=\"bookmark\">Les implants dentaires et le manque d&rsquo;os de la m\u00e2choire<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/all-on-4\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a><a href=\"https:\/\/sofiaimplantcentre.com\/bg\/all-on-4\/\" rel=\"bookmark\">En quoi consiste la restauration dentaire compl\u00e8te de la m\u00e2choire (ALL-ON-4 et ALL-ON-6) ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/success-in-all-on-4\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a> <a href=\"https:\/\/sofiaimplantcentre.com\/bg\/all-on-4-most-important\/\" rel=\"bookmark\">Les trois \u00e9l\u00e9ments primordiaux pour un traitement ALL-ON-4 ou ALL-ON-6 r\u00e9ussi ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/zirconium-and-zirconium\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a> <a href=\"https:\/\/sofiaimplantcentre.com\/bg\/zirconium\/\" rel=\"bookmark\">Le ZIRCONE et \u2026 le zircone<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/dental-laboratory\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a> <a href=\"https:\/\/sofiaimplantcentre.com\/bg\/dental-lab\/\" rel=\"bookmark\">Pourquoi un laboratoire dentaire moderne est-il n\u00e9cessaire pour un meilleur traitement ?<\/a><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/sofiaimplantcentre.com\/surgical-guides\/\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13788\" src=\"https:\/\/sofiaimplantcentre.com\/wp-content\/uploads\/2022\/03\/2-512-e1649689786111.webp\" alt=\"\" width=\"25\" height=\"25\" \/> <\/span><\/a> <a href=\"https:\/\/sofiaimplantcentre.com\/bg\/hirurgichni-vodachi\/\" rel=\"bookmark\">En quoi les guides chirurgicaux pour implants dentaires sont-ils si importants ?<\/a><\/p>\n<div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?2a86a1572c4e5994cd55d61e26\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, les implants dentaires sont devenus le moyen privil\u00e9gi\u00e9 de traiter les dents manquantes. Voici tout ce qu&rsquo;il faut savoir sur les implants dentaires.<\/p>\n","protected":false},"author":5,"featured_media":12525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[248,249,251,269],"tags":[260,293],"class_list":["post-13350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chirurgie-dentaire","category-implants-dentaires","category-planning-fr","category-all-on-4-6-fr","tag-implants-dentaires","tag-implants-dentaires-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/posts\/13350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/comments?post=13350"}],"version-history":[{"count":6,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/posts\/13350\/revisions"}],"predecessor-version":[{"id":26127,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/posts\/13350\/revisions\/26127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/media\/12525"}],"wp:attachment":[{"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/media?parent=13350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/categories?post=13350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sofiaimplantcentre.com\/fr\/wp-json\/wp\/v2\/tags?post=13350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}